{"id":9732,"date":"2025-05-02T11:06:14","date_gmt":"2025-05-02T09:06:14","guid":{"rendered":"https:\/\/devbox2.mc8pm.com\/masterpieces\/la-onda\/"},"modified":"2026-05-12T12:34:51","modified_gmt":"2026-05-12T10:34:51","slug":"la-onda","status":"publish","type":"page","link":"https:\/\/vanme.de\/fr\/masterpieces\/la-onda\/","title":{"rendered":"La Onda"},"content":{"rendered":"\n\n\n                        \n            \n            <section class=\"block-media cnt-1 block-media-mobile-sort- blockheight-laptop-100vh blockheight-tablet-80vh blockheight-mobile-80vh blockstyle-display block-media-width-\" style=\"margin-top: 0px\">\n\n                \n                \n                    \n                    <div class=\"media media-0 has-media\">\n\n                        \n\n                        \n                                                        <div class=\"s1x-video\">\n                                <video class=\"jshook-play-video-when-in-viewport cntrl-scroll-outside-viewport-when-ended\"\n                                       playsinline muted loop\n                                       width=\"1000\"\n                                       height=\"720\"\n                                       preload=\"none\"\n                                       data-bunny-hls-url=\"https:\/\/vz-83a9f633-61a.b-cdn.net\/1afd8cf6-c160-4c58-888e-ecb1520f046f\/playlist.m3u8\"                                       poster=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/LaOndaTrailer_FullHD_ohne-Text_30MB-poster.jpg\">\n                                    <source src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/LaOndaTrailer_FullHD_ohne-Text_30MB.mp4\">\n                                <\/video>\n                            <\/div>\n\n                        \n                        <div class=\"overlay s1x-absolute-100 has-media                            s1x-tovp-tablapdesk-                            s1x-tovp-mob-\n                            s1x-tovp-notext\">\n\n                            \n                            \n                            \n                            \n                            \n                            \n                        <\/div>\n\n                        \n                    <\/div>\n\n                \n            <\/section>\n\n            \n\n\n    <section class=\"block-text center area-align-center\" style=\"margin-top: 80px; max-width: 1300px\">\n\n        \n                                \n                            <h1 class=\"ff-bebas-ds80 ff-uppercase\" style=\"display:none\">La Onda<\/h1>\n                <img decoding=\"async\" class=\"headline-image\" src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/07\/Signature-LaOnda.png\" alt=\"La Onda Modellschriftzug\" style=\"width:100%; height:auto;\">\n                    \n                    <div class=\"ff-bebas-ds30\"><span class=\"ff-thin\">Mercedes Benz Sprinter<\/span><\/div>\n        \n        <div class=\"ff-bodytext \">\n            <p>Longueur 3 Hauteur 2 | 4 roues motrices | Ann\u00e9e de construction 2024<\/p>\n        <\/div>\n\n\n                \n    <\/section>\n\n\n\n\n    <section class=\"block-kpi\" style=\"margin-top: 80px;\">\n\n                                            \n                    <div class=\"kpi\">\n                        <div class=\"value ff-bebas-ds30\">7,7 m\u00b2<\/div>\n                        <div class=\"label ff-lakes-neue-cnd-ds22\">Surface de base<\/div>\n                    <\/div>\n\n                \n                    <div class=\"kpi\">\n                        <div class=\"value ff-bebas-ds30\">3<\/div>\n                        <div class=\"label ff-lakes-neue-cnd-ds22\">Places assises<\/div>\n                    <\/div>\n\n                \n                    <div class=\"kpi\">\n                        <div class=\"value ff-bebas-ds30\">3<\/div>\n                        <div class=\"label ff-lakes-neue-cnd-ds22\">Places de couchage<\/div>\n                    <\/div>\n\n                \n                    <div class=\"kpi\">\n                        <div class=\"value ff-bebas-ds30\">4400 KG<\/div>\n                        <div class=\"label ff-lakes-neue-cnd-ds22\">Masse totale<\/div>\n                    <\/div>\n\n                \n                    <div class=\"kpi\">\n                        <div class=\"value ff-bebas-ds30\">600KG<\/div>\n                        <div class=\"label ff-lakes-neue-cnd-ds22\">Charge utile (\u00e0 vide)<\/div>\n                    <\/div>\n\n                                    \n\n    <\/section>\n\n\n    <section class=\"block-text center area-align-center\" style=\"margin-top: 80px; max-width: 1600px\">\n\n        \n                                \n                                            <h2 class=\"ff-bebas-ds80 ff-uppercase hlsize-\">La vague de la perfection<\/h2>\n                    \n        \n        <div class=\"ff-bodytext \">\n            <p>Avec le projet \u00ab\u00a0La Onda\", VANME porte l&rsquo;am\u00e9nagement de camping-cars \u00e0 un tout autre niveau.<br \/>\nConstruit sur la base d&rsquo;un Mercedes Benz Sprinter L3H2 \u00e0 quatre roues motrices, ce v\u00e9hicule repr\u00e9sente ce qui na\u00eet lorsque l&rsquo;artisanat, le design et la technologie se fondent en un tout - un m\u00e9ga-yacht sur quatre roues.<\/p>\n<p>Chaque d\u00e9tail r\u00e9pond \u00e0 une vision claire : luxe, fonctionnalit\u00e9 et esth\u00e9tique en parfaite harmonie.<br \/>\nUn lit de pavillon, une implantation impressionnante et g\u00e9n\u00e9reuse - inspir\u00e9e de celle d&rsquo;un couple am\u00e9ricain - et un syst\u00e8me intelligent de maison intelligente font du voyage une exp\u00e9rience de haut niveau.<\/p>\n<p>\u00c0 l&rsquo;int\u00e9rieur, l&rsquo;Alcantara c\u00f4toie des surfaces aux finitions raffin\u00e9es, le plancher en li\u00e8ge v\u00e9ritable au design de yacht c\u00f4toie des meubles fabriqu\u00e9s avec pr\u00e9cision, chaque \u00e9l\u00e9ment est d&rsquo;une qualit\u00e9 sans compromis. Le coin salon et le poste de pilotage sont ennoblis par les mat\u00e9riaux les plus fins - l&rsquo;artisanat palpable dans sa forme la plus \u00e9l\u00e9gante. <\/p>\n<p>\u00c0 l&rsquo;ext\u00e9rieur aussi, La Onda fait une d\u00e9claration : un film ondul\u00e9 qui symbolise le mouvement, des jantes VANME Signature, un syst\u00e8me de son int\u00e9gr\u00e9 avec des excitateurs dans tout le v\u00e9hicule, un projecteur et un \u00e9cran - chaque d\u00e9tail t\u00e9moigne d&rsquo;une sophistication technique et d&rsquo;une conception visionnaire.<\/p>\n<p>La Onda est plus qu&rsquo;un camping-car - c&rsquo;est une \u0153uvre d&rsquo;art sur roues, cr\u00e9\u00e9e pour ceux qui recherchent l&rsquo;extraordinaire.<br \/>\nUne vague qui d\u00e9passe tout ce qui a \u00e9t\u00e9 possible jusqu&rsquo;\u00e0 pr\u00e9sent.<\/p>\n        <\/div>\n\n\n                \n    <\/section>\n\n\n\n    <section class=\"block-imageslider-100vw blockheight-16-9\" style=\"margin-top: 80px\">\n\n                            \n                <div class=\"jshook-swiper-imageslider-100vw swiper\" data-slidertype=\"fade\">\n                    <div class=\"swiper-wrapper\">\n\n                        \n                            <div class=\"swiper-slide\">\n\n                                \n                                <picture class=\"s1x-picture-cover jshook-provide-hq-after-dom-loaded\">\n                                    <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07871.jpg\"\n                                            width=\"1920\"\n                                            height=\"1080\">\n\n                                    \n                                    <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07871.jpg.webp\"\n                                            width=\"1920\"\n                                            height=\"1080\"\n                                            type=\"image\/webp\">\n\n                                                                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07871.jpg\"\n                                         width=\"1920\"\n                                         height=\"1080\"\n                                         alt=\"Der La Onda Campervan seitlich fotografiert mit Blick auf die Folierung\">\n                                <\/picture>\n\n\n                            <\/div>\n\n                        \n                            <div class=\"swiper-slide\">\n\n                                \n                                <picture class=\"s1x-picture-cover jshook-provide-hq-after-dom-loaded\">\n                                    <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07851.jpg\"\n                                            width=\"1920\"\n                                            height=\"1080\">\n\n                                    \n                                    <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07851.jpg.webp\"\n                                            width=\"1920\"\n                                            height=\"1080\"\n                                            type=\"image\/webp\">\n\n                                                                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07851.jpg\"\n                                         width=\"1920\"\n                                         height=\"1080\"\n                                         alt=\"Perfekte Seitenaufnahme des La Onda Campervans\">\n                                <\/picture>\n\n\n                            <\/div>\n\n                        \n                            <div class=\"swiper-slide\">\n\n                                \n                                <picture class=\"s1x-picture-cover jshook-provide-hq-after-dom-loaded\">\n                                    <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07900.jpg\"\n                                            width=\"1920\"\n                                            height=\"1080\">\n\n                                    \n                                    <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07900.jpg.webp\"\n                                            width=\"1920\"\n                                            height=\"1080\"\n                                            type=\"image\/webp\">\n\n                                                                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07900.jpg\"\n                                         width=\"1920\"\n                                         height=\"1080\"\n                                         alt=\"Der La Onda Campervan seitlich fotografiert\">\n                                <\/picture>\n\n\n                            <\/div>\n\n                        \n                            <div class=\"swiper-slide\">\n\n                                \n                                <picture class=\"s1x-picture-cover jshook-provide-hq-after-dom-loaded\">\n                                    <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07917.jpg\"\n                                            width=\"1920\"\n                                            height=\"1080\">\n\n                                    \n                                    <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07917.jpg.webp\"\n                                            width=\"1920\"\n                                            height=\"1080\"\n                                            type=\"image\/webp\">\n\n                                                                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07917.jpg\"\n                                         width=\"1920\"\n                                         height=\"1080\"\n                                         alt=\"Der La Onda Campervan aus der Drohnenperspektive\">\n                                <\/picture>\n\n\n                            <\/div>\n\n                        \n                            <div class=\"swiper-slide\">\n\n                                \n                                <picture class=\"s1x-picture-cover jshook-provide-hq-after-dom-loaded\">\n                                    <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC08029.jpg\"\n                                            width=\"1920\"\n                                            height=\"1080\">\n\n                                    \n                                    <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC08029.jpg.webp\"\n                                            width=\"1920\"\n                                            height=\"1080\"\n                                            type=\"image\/webp\">\n\n                                                                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC08029.jpg\"\n                                         width=\"1920\"\n                                         height=\"1080\"\n                                         alt=\"Au\u00dfenansicht des La Onda Campervans mit maritimer Folierung\">\n                                <\/picture>\n\n\n                            <\/div>\n\n                        \n                            <div class=\"swiper-slide\">\n\n                                \n                                <picture class=\"s1x-picture-cover jshook-provide-hq-after-dom-loaded\">\n                                    <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07939.jpg\"\n                                            width=\"1920\"\n                                            height=\"1080\">\n\n                                    \n                                    <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07939.jpg.webp\"\n                                            width=\"1920\"\n                                            height=\"1080\"\n                                            type=\"image\/webp\">\n\n                                                                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-360grad-slider-DSC07939.jpg\"\n                                         width=\"1920\"\n                                         height=\"1080\"\n                                         alt=\"Nahaufnahme der VANME Signature Felge auf dem Gel\u00e4nde des alten Kieswerkes\">\n                                <\/picture>\n\n\n                            <\/div>\n\n                        \n                    <\/div>\n\n                    <div class=\"swiper-pagination\"><\/div>\n\n                <\/div>\n\n                    \n    <\/section>\n\n\n    <section class=\"block-imageslider flickity-imageslider-carousel\" style=\"margin-top: 80px\">\n\n                                    \n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07411.jpg\"\n                                        width=\"915\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07411.jpg.webp\"\n                                        width=\"915\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07411.jpg\"\n                                        width=\"915\"\n                                        height=\"1400\">\n\n                                <img loading=\"lazy\" decoding=\"async\"                                         src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07411.jpg\"\n                                        width=\"915\"\n                                        height=\"1400\"\n                                        alt=\"Blick durch die Schiebet\u00fcr in den La Onda Campervan\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07159.jpg\"\n                                        width=\"1632\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07159.jpg.webp\"\n                                        width=\"1632\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07159.jpg\"\n                                        width=\"1632\"\n                                        height=\"1400\">\n\n                                <img loading=\"lazy\" decoding=\"async\"                                         src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07159.jpg\"\n                                        width=\"1632\"\n                                        height=\"1400\"\n                                        alt=\"Blick durch die Schiebet\u00fcr in den Camper mit Alcantara Sitzecke\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07184.jpg\"\n                                        width=\"1978\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07184.jpg.webp\"\n                                        width=\"1978\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07184.jpg\"\n                                        width=\"1978\"\n                                        height=\"1400\">\n\n                                <img loading=\"lazy\" decoding=\"async\"                                         src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07184.jpg\"\n                                        width=\"1978\"\n                                        height=\"1400\"\n                                        alt=\"Nahaufnahme der Tischplatte mit eingelassener LED Beleuchtung\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07191.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07191.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07191.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07191.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Meisterhafte Tischlerkunst mit eingearbeiteten Leds in Wellenform an Sitzgruppentisch und Decke\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07245.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07245.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07245.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07245.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Trockentrenntoilette auf einem Auszug im Heckbad\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07255.jpg\"\n                                        width=\"1681\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07255.jpg.webp\"\n                                        width=\"1681\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07255.jpg\"\n                                        width=\"1681\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07255.jpg\"\n                                        width=\"1681\"\n                                        height=\"1400\"\n                                        alt=\"Heckgarage mit Befestigungsl\u00f6sungen\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07259.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07259.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07259.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07259.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Nahaufnahme der DUschwanne\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07268.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07268.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07268.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07268.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Perfekt eingearbeitete Boxen in der Heckgarage\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07269.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07269.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07269.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07269.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Erste Hilfe Werkzeugkoffer f\u00fcr Fahrr\u00e4der\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07278.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07278.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07278.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07278.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Wei\u00dfes Waschbecken mit schwarzen Armaturen\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07301.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07301.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07301.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07301.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Duschboden im Campervan mit Heckgarage\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07321.jpg\"\n                                        width=\"1730\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07321.jpg.webp\"\n                                        width=\"1730\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07321.jpg\"\n                                        width=\"1730\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07321.jpg\"\n                                        width=\"1730\"\n                                        height=\"1400\"\n                                        alt=\"Heckbad im La Onda Campervan\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07326.jpg\"\n                                        width=\"1928\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07326.jpg.webp\"\n                                        width=\"1928\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07326.jpg\"\n                                        width=\"1928\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07326.jpg\"\n                                        width=\"1928\"\n                                        height=\"1400\"\n                                        alt=\"Ma\u00dfgeschneiderte Handt\u00fccher im maritimen Blau\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07330.jpg\"\n                                        width=\"1730\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07330.jpg.webp\"\n                                        width=\"1730\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07330.jpg\"\n                                        width=\"1730\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07330.jpg\"\n                                        width=\"1730\"\n                                        height=\"1400\"\n                                        alt=\"Perfekt in den Campervan integriertes Tablet mit Revotion Smart-Home-Software\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07342.jpg\"\n                                        width=\"1780\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07342.jpg.webp\"\n                                        width=\"1780\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07342.jpg\"\n                                        width=\"1780\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07342.jpg\"\n                                        width=\"1780\"\n                                        height=\"1400\"\n                                        alt=\"Schrankt\u00fcren mit Spiegeln im Campervan\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07345.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07345.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07345.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07345.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Dreckw\u00e4sche Fallloch im Schrank\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07349.jpg\"\n                                        width=\"989\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07349.jpg.webp\"\n                                        width=\"989\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07349.jpg\"\n                                        width=\"989\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07349.jpg\"\n                                        width=\"989\"\n                                        height=\"1400\"\n                                        alt=\"Dometic K\u00fchlschrank mit ge\u00f6ffneter T\u00fcr\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07366.jpg\"\n                                        width=\"1483\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07366.jpg.webp\"\n                                        width=\"1483\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07366.jpg\"\n                                        width=\"1483\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07366.jpg\"\n                                        width=\"1483\"\n                                        height=\"1400\"\n                                        alt=\"K\u00fcchenbereich im Campervan mit Blick in das Bad\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07367.jpg\"\n                                        width=\"1335\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07367.jpg.webp\"\n                                        width=\"1335\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07367.jpg\"\n                                        width=\"1335\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07367.jpg\"\n                                        width=\"1335\"\n                                        height=\"1400\"\n                                        alt=\"Magnetisch haftende Gew\u00fcrze im Campervan\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07371.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07371.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07371.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07371.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Gaskochfeld im La Onda Campervan\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07375.jpg\"\n                                        width=\"1730\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07375.jpg.webp\"\n                                        width=\"1730\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07375.jpg\"\n                                        width=\"1730\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07375.jpg\"\n                                        width=\"1730\"\n                                        height=\"1400\"\n                                        alt=\"Unser Highlight, ein Backofen im Campervan\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07384.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07384.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07384.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07384.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Im Interieur integrierter M\u00fclleimer\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07385.jpg\"\n                                        width=\"1483\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07385.jpg.webp\"\n                                        width=\"1483\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07385.jpg\"\n                                        width=\"1483\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07385.jpg\"\n                                        width=\"1483\"\n                                        height=\"1400\"\n                                        alt=\"Tassen mit Magnethalterung im Boden\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07337.jpg\"\n                                        width=\"989\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07337.jpg.webp\"\n                                        width=\"989\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07337.jpg\"\n                                        width=\"989\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07337.jpg\"\n                                        width=\"989\"\n                                        height=\"1400\"\n                                        alt=\"Magnetverschl\u00fcsse f\u00fcr Schrankt\u00fcren\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07394.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07394.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07394.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07394.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Perfekt eingearbeitete Sp\u00fcle im Campervan\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07401.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07401.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07401.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07401.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Speziell angefertigte Schublade f\u00fcr Besteck im Campervan\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07414.jpg\"\n                                        width=\"1780\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07414.jpg.webp\"\n                                        width=\"1780\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07414.jpg\"\n                                        width=\"1780\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07414.jpg\"\n                                        width=\"1780\"\n                                        height=\"1400\"\n                                        alt=\"Frontalansicht des heruntergelassenen Hubbetts im La Onda Campervan\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07425.jpg\"\n                                        width=\"1928\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07425.jpg.webp\"\n                                        width=\"1928\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07425.jpg\"\n                                        width=\"1928\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07425.jpg\"\n                                        width=\"1928\"\n                                        height=\"1400\"\n                                        alt=\"Seitliche Sicht des heruntergelassenen Hubbettes im La Onda Campervan\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07438.jpg\"\n                                        width=\"1483\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07438.jpg.webp\"\n                                        width=\"1483\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07438.jpg\"\n                                        width=\"1483\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07438.jpg\"\n                                        width=\"1483\"\n                                        height=\"1400\"\n                                        alt=\"Heruntergelassenes Hubbett im Campervan \">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07730.jpg\"\n                                        width=\"833\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07730.jpg.webp\"\n                                        width=\"833\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07730.jpg\"\n                                        width=\"833\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07730.jpg\"\n                                        width=\"833\"\n                                        height=\"1400\"\n                                        alt=\"Im Korkboden versteckte Airlineschiene im La Onda Campervan\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07790.jpg\"\n                                        width=\"2097\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07790.jpg.webp\"\n                                        width=\"2097\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07790.jpg\"\n                                        width=\"2097\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07790.jpg\"\n                                        width=\"2097\"\n                                        height=\"1400\"\n                                        alt=\"Blick durch den Vampervan La Onda vom Cockpit aus\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07796.jpg\"\n                                        width=\"2097\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07796.jpg.webp\"\n                                        width=\"2097\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07796.jpg\"\n                                        width=\"2097\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07796.jpg\"\n                                        width=\"2097\"\n                                        height=\"1400\"\n                                        alt=\"Sofabereich im La Onda Campervan\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07800.jpg\"\n                                        width=\"2097\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07800.jpg.webp\"\n                                        width=\"2097\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07800.jpg\"\n                                        width=\"2097\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07800.jpg\"\n                                        width=\"2097\"\n                                        height=\"1400\"\n                                        alt=\"Holztreppe mit 'VANME' Schriftzug\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07813.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07813.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07813.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07813.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Moderne K\u00fcchenschr\u00e4nke mit Holzdetails\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07397.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07397.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07397.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07397.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Offene Schublade mit Geschirr und Holzbrett\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07147.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07147.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07147.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-interieur-slider-DSC07147.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"La Onda\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    \n    <\/section>\n\n\n\n    <section class=\"block-text left area-align-left\" style=\"margin-top: 80px; max-width: unset\">\n\n        \n                                \n                                            <h2 class=\"ff-bebas-ds80 ff-uppercase hlsize-\"><span class=\"ff-thin\">L&rsquo;<\/span> art <span class=\"ff-thin\">du voyage<\/span> - revisit\u00e9<\/h2>\n                    \n        \n        <div class=\"ff-bodytext \">\n            <p>Avec La Onda, VANME a cr\u00e9\u00e9 un v\u00e9hicule o\u00f9 l&rsquo;artisanat et le design se fondent dans une nouvelle forme d&rsquo;esth\u00e9tique. Chaque surface, chaque ligne, chaque lumi\u00e8re - tout suit un mouvement fluide, inspir\u00e9 par la force et l&rsquo;\u00e9l\u00e9gance des vagues. <\/p>\n<p>Le point central est le plafond en ch\u00eane v\u00e9ritable, dans lequel un motif de vagues en placage noir a \u00e9t\u00e9 incrust\u00e9 avec pr\u00e9cision - un chef-d&rsquo;\u0153uvre de fabrication qui transporte la dynamique de la mer \u00e0 l&rsquo;int\u00e9rieur. Le long de cette structure, une bande de luminaires LED, \u00e9galement en forme de vagues douces, baigne l&rsquo;espace d&rsquo;une lumi\u00e8re chaude et vivante. <\/p>\n<p>\u00c0 la demande du client, ce concept de design a \u00e9t\u00e9 pouss\u00e9 jusque dans les moindres d\u00e9tails : La table mobile reprend le motif de la vague - avec des lignes noires int\u00e9gr\u00e9es et un \u00e9clairage LED int\u00e9gr\u00e9 qui prolonge le mouvement de la lumi\u00e8re. Le poste de conduite a lui aussi \u00e9t\u00e9 trait\u00e9 dans un design en forme de vagues, recouvert d&rsquo;Alcantara fin et agr\u00e9ment\u00e9 d&rsquo;\u00e9l\u00e9ments en aluminium lasur\u00e9 qui scintillent discr\u00e8tement et compl\u00e8tent \u00e9l\u00e9gamment le langage des formes. <\/p>\n<p>Le plan d&rsquo;\u00e9tage impressionne par sa g\u00e9n\u00e9rosit\u00e9 exceptionnelle et sa structure claire. Il est compl\u00e9t\u00e9 par un mini-cin\u00e9ma int\u00e9gr\u00e9 avec vid\u00e9oprojecteur et syst\u00e8me de sonorisation, qui transforme l&rsquo;int\u00e9rieur en une exp\u00e9rience de divertissement priv\u00e9e - avec style, discr\u00e9tion et une r\u00e9alisation technique parfaite. <\/p>\n<p>De l&rsquo;ext\u00e9rieur, La Onda poursuit son concept de design de mani\u00e8re coh\u00e9rente : un pelliculage au motif de vagues, un look tout-terrain enti\u00e8rement \u00e9quip\u00e9 et des jantes VANME Signature en font un v\u00e9ritable point de mire - puissant, noble et incomparable.<\/p>\n<p>La Onda est plus qu&rsquo;un camping-car.<br \/>\nC&rsquo;est une \u0153uvre d&rsquo;art en mouvement - cr\u00e9\u00e9e pour ceux qui ressentent le design, admirent la technologie et aiment la libert\u00e9.<\/p>\n        <\/div>\n\n\n                \n    <\/section>\n\n\n\n\n\n                        \n            \n            <section class=\"block-media cnt-1 block-media-mobile-sort- blockheight-laptop-16-9 blockheight-tablet-1-1 blockheight-mobile-1-1 blockstyle-highlight block-media-width-\" style=\"margin-top: 80px\">\n\n                \n                \n                    \n                    <div class=\"media media-0 has-media\">\n\n                        \n\n                        \n                            \n                            <picture class=\"s1x-picture-cover jshook-provide-hq-after-dom-loaded \">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-fhd.jpg\"\n                                        width=\"1920\"\n                                        height=\"1281\">\n\n                                \n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-fhd.jpg.webp\"\n                                        width=\"1920\"\n                                        height=\"1281\"\n                                        type=\"image\/webp\">\n\n                                                                <img decoding=\"async\" loading=\"lazy\"\n                                     src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-fhd.jpg\"\n                                     width=\"1920\"\n                                     height=\"1281\"\n                                     alt=\"HDR Cockpitaufnahme der PS Sattlerei Arbeiten im La Onda Campervan\">\n                            <\/picture>\n\n                        \n                        <div class=\"overlay s1x-absolute-100 has-media                            s1x-tovp-tablapdesk-cc                            s1x-tovp-mob-cc\n                            \">\n\n                            \n                            \n                            \n                            \n                            \n                            \n                        <\/div>\n\n                        \n                    <\/div>\n\n                \n            <\/section>\n\n            \n\n\n    <section class=\"block-text center area-align-left\" style=\"margin-top: 80px; max-width: unset\">\n\n        \n                                \n                                            <h2 class=\"ff-bebas-ds80 ff-uppercase hlsize-\">La Onda - <span class=\"ff-thin\">une vague de<\/span> passion, de pr\u00e9cision <span class=\"ff-thin\">et<\/span> de perfection<\/h2>\n                    \n        \n        <div class=\"ff-bodytext \">\n            <p>De la premi\u00e8re id\u00e9e au dernier boulon, La Onda n&rsquo;\u00e9tait pas un projet d&rsquo;am\u00e9nagement ordinaire - c&rsquo;\u00e9tait le processus de construction d&rsquo;un yacht. Un chef-d&rsquo;\u0153uvre qui d\u00e9place sur des roues ce qui est habituellement chez soi sur l&rsquo;eau : calme, \u00e9l\u00e9gance, pr\u00e9cision technique et qualit\u00e9 sans compromis. <\/p>\n<p>Comme dans la construction exclusive d&rsquo;un bateau, chaque d\u00e9tail a \u00e9t\u00e9 con\u00e7u, fabriqu\u00e9 et ajust\u00e9 \u00e0 la main - avec une coh\u00e9rence que l&rsquo;on sent, que l&rsquo;on voit et que l&rsquo;on entend.<br \/>\nLe plafond en bois v\u00e9ritable avec placage ondul\u00e9 encastr\u00e9, la bande lumineuse compos\u00e9e de LED en mouvement fluide, les composants en aluminium affin\u00e9, le cockpit recouvert d&rsquo;Alcantara et le sol en li\u00e8ge au design de yacht forment une harmonie de mat\u00e9riaux, de formes et de lumi\u00e8re.<\/p>\n<p>Il est \u00e9quip\u00e9 d&rsquo;un cin\u00e9ma int\u00e9gr\u00e9 avec vid\u00e9oprojecteur et syst\u00e8me audio, ainsi que d&rsquo;un ext\u00e9rieur tout-terrain avec un film ondul\u00e9 et des jantes VANME Signature reconnaissables entre toutes - l&rsquo;expression de la puissance, du design et de la personnalit\u00e9.<\/p>\n<p>La Onda est le r\u00e9sultat d&rsquo;une exigence qui va au-del\u00e0 de l&rsquo;ordinaire.<br \/>\nUn v\u00e9hicule qui montre ce qui r\u00e9sulte de la rencontre entre la construction de yachts, la technique et l&rsquo;\u00e9motion - un chef-d&rsquo;\u0153uvre roulant, cr\u00e9\u00e9 pour tous ceux qui \u00e9l\u00e8vent le voyage au rang d&rsquo;art.<\/p>\n        <\/div>\n\n\n                \n    <\/section>\n\n\n\n\n\n                        \n            \n            <section class=\"block-media cnt-1 block-media-mobile-sort- blockheight-laptop-100vh blockheight-tablet-1-1 blockheight-mobile-1-1 blockstyle-display block-media-width-\" style=\"margin-top: 0px\">\n\n                \n                \n                    \n                    <div class=\"media media-0 has-media\">\n\n                        \n\n                        \n                                                        <div class=\"s1x-video\">\n                                <video class=\"jshook-play-video-when-in-viewport \"\n                                       playsinline muted loop\n                                       width=\"1000\"\n                                       height=\"720\"\n                                       preload=\"none\"\n                                       data-bunny-hls-url=\"https:\/\/vz-83a9f633-61a.b-cdn.net\/61bfd0ad-a6af-4444-a78c-d8c8a770516e\/playlist.m3u8\"                                       poster=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/11\/laonda_kiesgrube_30MB_ohne_text-poster.m.jpg\">\n                                    <source src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/11\/laonda_kiesgrube_30MB_ohne_text.mp4\">\n                                <\/video>\n                            <\/div>\n\n                        \n                        <div class=\"overlay s1x-absolute-100 has-media                            s1x-tovp-tablapdesk-                            s1x-tovp-mob-\n                            s1x-tovp-notext\">\n\n                            \n                            \n                            \n                            \n                            \n                            \n                        <\/div>\n\n                        \n                    <\/div>\n\n                \n            <\/section>\n\n            \n\n\n    <section class=\"block-imageslider flickity-imageslider-carousel\" style=\"margin-top: 80px\">\n\n                                    \n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07096-1.jpg\"\n                                        width=\"1946\"\n                                        height=\"1300\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07096-1.jpg.webp\"\n                                        width=\"1946\"\n                                        height=\"1300\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07096-1.jpg\"\n                                        width=\"1946\"\n                                        height=\"1300\">\n\n                                <img loading=\"lazy\" decoding=\"async\"                                         src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07096-1.jpg\"\n                                        width=\"1946\"\n                                        height=\"1300\"\n                                        alt=\"Kopfst\u00fctze mit La Onda und VANME Logo\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07085.jpg\"\n                                        width=\"989\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07085.jpg.webp\"\n                                        width=\"989\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07085.jpg\"\n                                        width=\"989\"\n                                        height=\"1400\">\n\n                                <img loading=\"lazy\" decoding=\"async\"                                         src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07085.jpg\"\n                                        width=\"989\"\n                                        height=\"1400\"\n                                        alt=\"In Wunschfarbe lackierter Kranz f\u00fcr Start\/Stop Schalter im Mercedes Sprinter\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07093.jpg\"\n                                        width=\"1632\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07093.jpg.webp\"\n                                        width=\"1632\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07093.jpg\"\n                                        width=\"1632\"\n                                        height=\"1400\">\n\n                                <img loading=\"lazy\" decoding=\"async\"                                         src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07093.jpg\"\n                                        width=\"1632\"\n                                        height=\"1400\"\n                                        alt=\"In Wunschfarbe lackierte Elemente im Cockpit des Campervans\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07081.jpg\"\n                                        width=\"742\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07081.jpg.webp\"\n                                        width=\"742\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07081.jpg\"\n                                        width=\"742\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07081.jpg\"\n                                        width=\"742\"\n                                        height=\"1400\"\n                                        alt=\"In Wunschfarbe lackierter Lautst\u00e4rkeschalter im Cockpit des Campervans\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07082.jpg\"\n                                        width=\"1483\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07082.jpg.webp\"\n                                        width=\"1483\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07082.jpg\"\n                                        width=\"1483\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07082.jpg\"\n                                        width=\"1483\"\n                                        height=\"1400\"\n                                        alt=\"In Wunschfarbe lackierter L\u00fcftungsring im Cockpit des Campervans\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07140.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07140.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07140.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07140.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Von der PS Sattlerei veredeltes Cockpit im La Onda Campervan\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07083.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07083.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07083.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07083.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"In Wunschfarbe lackierter Mercedes Stern auf dem Multifunktionslenkrad des Campervans\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    <div class=\"carousel-cell\">\n\n                        \n                        \n                            \n                            <picture class=\"jshook-provide-hq-after-dom-loaded\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07095.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07095.jpg.webp\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        type=\"image\/webp\">\n\n                                <source srcset=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07095.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\">\n\n                                <img decoding=\"async\" loading=\"lazy\"                                        src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-cockpit-slider-DSC07095.jpg\"\n                                        width=\"2096\"\n                                        height=\"1400\"\n                                        alt=\"Wellendesign des La Onda Campervans auf den Alcantara Sitzpolstern\">\n                            <\/picture>\n\n\n                        \n                    <\/div>\n\n                \n                    \n    <\/section>\n\n\n\n    <section class=\"block-details\" style=\"margin-top: 80px;\">\n\n                    <h2 class=\"ff-bebas-ds65 ff-uppercase\">Fabriqu\u00e9 par VanMe<\/h2>\n        \n        <div class=\"block-inner\">\n\n                                                            \n                        <div class=\"detail-section\">\n                            <h3 class=\"headline ff-uppercase ff-bebas-ds30\">Int\u00e9rieur<\/h3>\n                            <div class=\"details\">\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Canap\u00e9 dans l&rsquo;entr\u00e9e                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Bar ext\u00e9rieur extensible avec glaci\u00e8re et verres                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Lit de pavillon \u00e9lectrique                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Cuisine avec cuisini\u00e8re \u00e0 gaz 3 feux et four                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Armoire avec goulotte pour le linge                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Salle de bain compl\u00e8te avec papier peint \u00e0 motif de vagues et lavabo \u00e9l\u00e9gant                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Garage arri\u00e8re avec outils                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Sol en li\u00e8ge v\u00e9ritable de style yacht                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Table \u00e9clair\u00e9e en forme de vague                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Cockpit et si\u00e8ges en finition Alcantara                                    <\/div>\n\n                                                            <\/div>\n\n                        <\/div>\n\n                    \n                        <div class=\"detail-section\">\n                            <h3 class=\"headline ff-uppercase ff-bebas-ds30\">Ext\u00e9rieur<\/h3>\n                            <div class=\"details\">\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Peinture Raptor sur toutes les pi\u00e8ces rapport\u00e9es p\u00e9riph\u00e9riques                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Filmage partiel en design ondul\u00e9                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Compartiment de rangement externe dans le soubassement avec douche ext\u00e9rieure                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Spoiler de capot et finitions de passage de roue                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        \u00c9clairage lat\u00e9ral \u00e0 LED noir                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Maxx Fan Lanterneau avec ventilateur                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Ventilateur de toit Maxx Dome dans la salle de bain                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Lanterneau au-dessus du lit Dometic Medi Heki de 700 x 500 mm                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Store \u00e9lectrique Fiamma F80S                                      <\/div>\n\n                                                            <\/div>\n\n                        <\/div>\n\n                    \n                        <div class=\"detail-section\">\n                            <h3 class=\"headline ff-uppercase ff-bebas-ds30\">Racks et roues<\/h3>\n                            <div class=\"details\">\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Jeu de 5 roues avec jante VANME Signature 18 pouces et pneu BFGoodrich All Terrain T\/A KO3 265\/65 R18                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Dutch Vanparts barres de toit avec plateforme et LED \u00e0 l&rsquo;avant                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Dutch Vanparts Porte-roue de secours sur la porte arri\u00e8re                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Dutch Vanparts Planche multiflex sur le hayon avec \u00e9chelle                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Arceau avant Delta 4&#215;4                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Dutch Vanparts Rockslider avec marchepied                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Marchepieds sur l&rsquo;attelage de remorque                                    <\/div>\n\n                                                            <\/div>\n\n                        <\/div>\n\n                    \n                        <div class=\"detail-section\">\n                            <h3 class=\"headline ff-uppercase ff-bebas-ds30\">Technique et son<\/h3>\n                            <div class=\"details\">\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Batterie lithium 480 Ah avec technologie de booster de charge 60 A de Victron                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Victron Multiplus 12\/2000\/80 (chargeur, onduleur, circuit prioritaire)                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Prise de quai                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Syst\u00e8me solaire de 300 watts avec panneaux solaires accessibles                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Revotion Syst\u00e8me de maison intelligente                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        \u00c9clairage indirect par LED sur tous les contours du meuble                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        R\u00e9servoir d&rsquo;eau douce de 160 litres                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Alp Filter Syst\u00e8me de filtration d&rsquo;eau                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        R\u00e9chaud \u00e0 gaz \u00e0 3 feux avec four                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        R\u00e9frig\u00e9rateur \u00e0 compresseur de 90 litres Dometic Rc10.4 90 avec double charni\u00e8re                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        \u00c9cran de projection avec Bluetooth                                      <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Antenne Wifi 5G                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Fermeture des portes avec des \u00e9lectro-aimants qui ferment automatiquement toutes les portes et les tiroirs                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Caisson de basses sous le si\u00e8ge du passager avant                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Panneau de commande Mutlifonctionnel avec cinq modes                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Syst\u00e8me audio Audiotec Fischer i7 dans le cockpit                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        3 zones d&rsquo;excitation dans et autour du v\u00e9hicule pour un son partout dans le v\u00e9hicule                                    <\/div>\n\n                                                            <\/div>\n\n                        <\/div>\n\n                    \n                        <div class=\"detail-section\">\n                            <h3 class=\"headline ff-uppercase ff-bebas-ds30\">Sp\u00e9cialit\u00e9s<\/h3>\n                            <div class=\"details\">\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Un artisanat unique pour le rev\u00eatement des plafonds                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Tsich \u00e9clair\u00e9 au design ondul\u00e9                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Les mat\u00e9riaux les plus nobles sur toutes les surfaces                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Lit de pavillon \u00e9clectique \u00e0 l&rsquo;avant du v\u00e9hicule                                      <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Syst\u00e8me de son et de divertissement                                    <\/div>\n\n                                \n                                    <div class=\"detail ff-bodytext\">\n                                        Le plan donne l&rsquo;impression de vivre dans un appartement.                                    <\/div>\n\n                                                            <\/div>\n\n                        <\/div>\n\n                                                \n        <\/div>\n\n    <\/section>\n\n\n    <section class=\"block-contact\" style=\"margin-top: 80px\">\n\n\n        <div class=\"block-inner\">\n\n                            <div class=\"bookmark\">\n                    <div class=\"cssimg-bookmark cssimg-contain-center-norepeat jshook-bookmark-add\"\n                         data-bookmark-headline=\"Chef-d&#039;\u0153uvre &gt; La Onda\"\n                         data-bookmark-content=\"J&#039;ai aim\u00e9 le Mercedes Benz Sprinter Am\u00e9nagement Camper La Onda\">\n                    <\/div>\n                    <div class=\"text ff-bodytext\">La Onda pour une demande d&rsquo;information<\/div>\n                <\/div>\n\n            \n\n                            <div class=\"text ff-bodytext\">La Onda r\u00e9veille le campeur qui sommeille en vous ? Contactez-nous pour discuter de votre projet. <\/div>\n                <a class=\"s1x-button btn-white-do\" href=\"https:\/\/vanme.de\/fr\/contact\/\">\n                    Contact                <\/a>\n            \n        <\/div>\n\n        \n        <picture class=\"s1x-picture-cover-absolute jshook-provide-hq-after-dom-loaded\">\n            <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-contact-DSC07580.jpg\"\n                    width=\"1920\"\n                    height=\"707\">\n\n            \n            <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-contact-DSC07580.jpg.webp\"\n                    width=\"1920\"\n                    height=\"707\"\n                    type=\"image\/webp\">\n\n                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/laonda-contact-DSC07580.jpg\"\n                 width=\"1920\"\n                 height=\"707\"\n                 alt=\"Abstrakte schwarze Wellen mit Glanz\">\n        <\/picture>\n\n\n    <\/section>\n\n\n\n    <section class=\"block-breadcrumb center area-align-\" style=\"margin-top: 40px; max-width: ;\">\n\n        <nav aria-label=\"breadcrumbs\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Accueil<\/span><\/p><\/nav>\n    <\/section>\n\n\n\n\n\n                        \n            \n            <section class=\"block-media cnt-1 block-media-mobile-sort- blockheight-laptop-60vh blockheight-tablet-60vh blockheight-mobile-1-1 blockstyle-highlight block-media-width-\" style=\"margin-top: 40px\">\n\n                \n                \n                    \n                    <div class=\"media media-0 has-media\">\n\n                        \n\n                        \n                            \n                            <picture class=\"s1x-picture-cover jshook-provide-hq-after-dom-loaded darken-image\">\n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/startseite-masterpieces-hochkant-lightarrow-retouched.jpg\"\n                                        width=\"1500\"\n                                        height=\"1700\">\n\n                                \n                                <source srcset-hq=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/startseite-masterpieces-hochkant-lightarrow-retouched.jpg.webp\"\n                                        width=\"1500\"\n                                        height=\"1700\"\n                                        type=\"image\/webp\">\n\n                                                                <img decoding=\"async\" loading=\"lazy\"\n                                     src=\"https:\/\/vanme.de\/wp-content\/uploads\/2025\/10\/startseite-masterpieces-hochkant-lightarrow-retouched.jpg\"\n                                     width=\"1500\"\n                                     height=\"1700\"\n                                     alt=\"\">\n                            <\/picture>\n\n                        \n                        <div class=\"overlay s1x-absolute-100 has-media                            s1x-tovp-tablapdesk-cc                            s1x-tovp-mob-cc\n                            \">\n\n                            <div class='preheadline ff-bebas-ds30'><span class=\"ff-uppercase ff-thin\">Plus de pi\u00e8ces ma\u00eetresses<\/span><\/div>\n                            <div class='headline ff-bebas-ds65 ff-uppercase''>Light Arrow<\/div>\n                            \n                            \n                            <div class='text ff-bodytext'><p>Avec la \u00ab\u00a0Light Arrow\", une coop\u00e9ration exclusive a donn\u00e9 naissance \u00e0 un v\u00e9hicule qui allie design, artisanat et dynamisme de mani\u00e8re unique. Une ligne pr\u00e9cise et claire traverse tout le concept comme une fl\u00e8che - puissante, \u00e9l\u00e9gante et rectiligne sans compromis. <\/p>\n<\/div>\n                            <a class='s1x-button btn-white-do' href='https:\/\/vanme.de\/fr\/masterpieces\/fleche-legere\/'>En savoir plus<\/a>\n                        <\/div>\n\n                        \n                    <\/div>\n\n                \n            <\/section>\n\n            \n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":14828,"parent":9583,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9732","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/vanme.de\/fr\/wp-json\/wp\/v2\/pages\/9732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanme.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vanme.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vanme.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vanme.de\/fr\/wp-json\/wp\/v2\/comments?post=9732"}],"version-history":[{"count":27,"href":"https:\/\/vanme.de\/fr\/wp-json\/wp\/v2\/pages\/9732\/revisions"}],"predecessor-version":[{"id":25132,"href":"https:\/\/vanme.de\/fr\/wp-json\/wp\/v2\/pages\/9732\/revisions\/25132"}],"up":[{"embeddable":true,"href":"https:\/\/vanme.de\/fr\/wp-json\/wp\/v2\/pages\/9583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vanme.de\/fr\/wp-json\/wp\/v2\/media\/14828"}],"wp:attachment":[{"href":"https:\/\/vanme.de\/fr\/wp-json\/wp\/v2\/media?parent=9732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}